{"id":498,"date":"2022-11-22T17:40:42","date_gmt":"2022-11-22T16:40:42","guid":{"rendered":"https:\/\/ski.cerknica.net\/?p=498"},"modified":"2022-11-22T17:43:41","modified_gmt":"2022-11-22T16:43:41","slug":"prvi-sneg","status":"publish","type":"post","link":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/","title":{"rendered":"Prvi sneg"},"content":{"rendered":"\n<p>Iskreno se veselimo, da nam je narava letos postregla s prvim snegom teden hitreje kot lani. Pridna ekipa smu\u010darskega kluba Cerknica je pravo\u010dasno poskrbela za pripravo vle\u010dnice na Slivnici, prav tako sta pripravljena oba ratraka in sne\u017ena topova v biatlonskem centru. <\/p>\n\n\n\n<p>Se kmalu vidimo na zimskih nor\u010dijah! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iskreno se veselimo, da nam je narava letos postregla s prvim snegom teden hitreje kot lani. Pridna ekipa smu\u010darskega kluba Cerknica je pravo\u010dasno poskrbela za pripravo vle\u010dnice na Slivnici, prav tako sta pripravljena oba ratraka in sne\u017ena topova v biatlonskem centru. Se kmalu vidimo na zimskih nor\u010dijah!<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[43,26,42,44],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prvi sneg - Smu\u010darski klub Cerknica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prvi sneg - Smu\u010darski klub Cerknica\" \/>\n<meta property=\"og:description\" content=\"Iskreno se veselimo, da nam je narava letos postregla s prvim snegom teden hitreje kot lani. Pridna ekipa smu\u010darskega kluba Cerknica je pravo\u010dasno poskrbela za pripravo vle\u010dnice na Slivnici, prav tako sta pripravljena oba ratraka in sne\u017ena topova v biatlonskem centru. Se kmalu vidimo na zimskih nor\u010dijah!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/\" \/>\n<meta property=\"og:site_name\" content=\"Smu\u010darski klub Cerknica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/skcerknica\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-22T16:40:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-22T16:43:41+00:00\" \/>\n<meta name=\"author\" content=\"Leon Zalar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leon Zalar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/\"},\"author\":{\"name\":\"Leon Zalar\",\"@id\":\"https:\/\/ski.cerknica.net\/#\/schema\/person\/d3746bf9cf1c47213f020919cf9c44e4\"},\"headline\":\"Prvi sneg\",\"datePublished\":\"2022-11-22T16:40:42+00:00\",\"dateModified\":\"2022-11-22T16:43:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/\"},\"wordCount\":54,\"publisher\":{\"@id\":\"https:\/\/ski.cerknica.net\/#organization\"},\"keywords\":[\"biatlonski center\",\"sneg\",\"vle\u010dnica\",\"zima\"],\"articleSection\":[\"Splo\u0161no\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/\",\"url\":\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/\",\"name\":\"Prvi sneg - Smu\u010darski klub Cerknica\",\"isPartOf\":{\"@id\":\"https:\/\/ski.cerknica.net\/#website\"},\"datePublished\":\"2022-11-22T16:40:42+00:00\",\"dateModified\":\"2022-11-22T16:43:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ski.cerknica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prvi sneg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ski.cerknica.net\/#website\",\"url\":\"https:\/\/ski.cerknica.net\/\",\"name\":\"Smu\u010darski klub Cerknica\",\"description\":\"Klub veselih smu\u010darjev :)\",\"publisher\":{\"@id\":\"https:\/\/ski.cerknica.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ski.cerknica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ski.cerknica.net\/#organization\",\"name\":\"Smu\u010darski klub Cerknica\",\"url\":\"https:\/\/ski.cerknica.net\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/skcerknica\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ski.cerknica.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2017\/10\/logo_black.jpg\",\"contentUrl\":\"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2017\/10\/logo_black.jpg\",\"width\":950,\"height\":960,\"caption\":\"Smu\u010darski klub Cerknica\"},\"image\":{\"@id\":\"https:\/\/ski.cerknica.net\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ski.cerknica.net\/#\/schema\/person\/d3746bf9cf1c47213f020919cf9c44e4\",\"name\":\"Leon Zalar\",\"url\":\"https:\/\/ski.cerknica.net\/index.php\/author\/leonz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prvi sneg - Smu\u010darski klub Cerknica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/","og_locale":"en_US","og_type":"article","og_title":"Prvi sneg - Smu\u010darski klub Cerknica","og_description":"Iskreno se veselimo, da nam je narava letos postregla s prvim snegom teden hitreje kot lani. Pridna ekipa smu\u010darskega kluba Cerknica je pravo\u010dasno poskrbela za pripravo vle\u010dnice na Slivnici, prav tako sta pripravljena oba ratraka in sne\u017ena topova v biatlonskem centru. Se kmalu vidimo na zimskih nor\u010dijah!","og_url":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/","og_site_name":"Smu\u010darski klub Cerknica","article_publisher":"https:\/\/www.facebook.com\/skcerknica\/","article_published_time":"2022-11-22T16:40:42+00:00","article_modified_time":"2022-11-22T16:43:41+00:00","author":"Leon Zalar","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Leon Zalar","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/#article","isPartOf":{"@id":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/"},"author":{"name":"Leon Zalar","@id":"https:\/\/ski.cerknica.net\/#\/schema\/person\/d3746bf9cf1c47213f020919cf9c44e4"},"headline":"Prvi sneg","datePublished":"2022-11-22T16:40:42+00:00","dateModified":"2022-11-22T16:43:41+00:00","mainEntityOfPage":{"@id":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/"},"wordCount":54,"publisher":{"@id":"https:\/\/ski.cerknica.net\/#organization"},"keywords":["biatlonski center","sneg","vle\u010dnica","zima"],"articleSection":["Splo\u0161no"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/","url":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/","name":"Prvi sneg - Smu\u010darski klub Cerknica","isPartOf":{"@id":"https:\/\/ski.cerknica.net\/#website"},"datePublished":"2022-11-22T16:40:42+00:00","dateModified":"2022-11-22T16:43:41+00:00","breadcrumb":{"@id":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ski.cerknica.net\/index.php\/2022\/11\/22\/prvi-sneg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ski.cerknica.net\/"},{"@type":"ListItem","position":2,"name":"Prvi sneg"}]},{"@type":"WebSite","@id":"https:\/\/ski.cerknica.net\/#website","url":"https:\/\/ski.cerknica.net\/","name":"Smu\u010darski klub Cerknica","description":"Klub veselih smu\u010darjev :)","publisher":{"@id":"https:\/\/ski.cerknica.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ski.cerknica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ski.cerknica.net\/#organization","name":"Smu\u010darski klub Cerknica","url":"https:\/\/ski.cerknica.net\/","sameAs":["https:\/\/www.facebook.com\/skcerknica\/"],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ski.cerknica.net\/#\/schema\/logo\/image\/","url":"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2017\/10\/logo_black.jpg","contentUrl":"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2017\/10\/logo_black.jpg","width":950,"height":960,"caption":"Smu\u010darski klub Cerknica"},"image":{"@id":"https:\/\/ski.cerknica.net\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ski.cerknica.net\/#\/schema\/person\/d3746bf9cf1c47213f020919cf9c44e4","name":"Leon Zalar","url":"https:\/\/ski.cerknica.net\/index.php\/author\/leonz\/"}]}},"_links":{"self":[{"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/posts\/498"}],"collection":[{"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/comments?post=498"}],"version-history":[{"count":3,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/posts\/498\/revisions"}],"predecessor-version":[{"id":501,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/posts\/498\/revisions\/501"}],"wp:attachment":[{"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/media?parent=498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/categories?post=498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/tags?post=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}