{"id":617,"date":"2024-03-15T11:21:00","date_gmt":"2024-03-15T10:21:00","guid":{"rendered":"https:\/\/ski.cerknica.net\/?p=617"},"modified":"2024-03-29T11:28:01","modified_gmt":"2024-03-29T10:28:01","slug":"manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji","status":"publish","type":"post","link":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/","title":{"rendered":"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji"},"content":{"rendered":"\n<p>Na mladinskem svetovnem prvenstvu, ki je od 23. februarja do 2. marca 2024 potekalo v Otep\u00e4\u00e4ju, Estonija, je slovenske barve zastopala tudi na\u0161a biatlonka <strong>Manca Caserman<\/strong>. Na vseh treh preizku\u0161njah je od slovenskih predstavnic dosegla najbolj\u0161o uvrstitev: 12. mesto na tekmi posamezno 10 km, 17. mesto na sprintu 6 km in 20. mesto na skupinski 9 km. Nastopila je tudi v dveh \u0161tafetnih preizku\u0161njah; na \u017eenski \u0161tafeti 3&#215;6 km je dosegla 13. mesto, na me\u0161ani \u0161tafeti 4&#215;6 km pa 8. mesto.<\/p>\n\n\n\n<p>Iskrene \u010destitke Manci in ostalim slovenskim predstavnikom!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" src=\"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/image.png\" alt=\"\" class=\"wp-image-620\" width=\"841\" height=\"846\" srcset=\"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/image.png 661w, https:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/image-298x300.png 298w, https:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/image-150x150.png 150w, https:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/image-100x100.png 100w, https:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/image-64x64.png 64w, https:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/image-308x310.png 308w, https:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/image-104x105.png 104w\" sizes=\"(max-width: 841px) 100vw, 841px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Na mladinskem svetovnem prvenstvu, ki je od 23. februarja do 2. marca 2024 potekalo v Otep\u00e4\u00e4ju, Estonija, je slovenske barve zastopala tudi na\u0161a biatlonka Manca Caserman. Na vseh treh preizku\u0161njah je od slovenskih predstavnic dosegla najbolj\u0161o uvrstitev: 12. mesto na tekmi posamezno 10 km, 17. mesto na sprintu 6 km in 20. mesto na skupinski [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[17,60,65],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji - Smu\u010darski klub Cerknica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji - Smu\u010darski klub Cerknica\" \/>\n<meta property=\"og:description\" content=\"Na mladinskem svetovnem prvenstvu, ki je od 23. februarja do 2. marca 2024 potekalo v Otep\u00e4\u00e4ju, Estonija, je slovenske barve zastopala tudi na\u0161a biatlonka Manca Caserman. Na vseh treh preizku\u0161njah je od slovenskih predstavnic dosegla najbolj\u0161o uvrstitev: 12. mesto na tekmi posamezno 10 km, 17. mesto na sprintu 6 km in 20. mesto na skupinski [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/\" \/>\n<meta property=\"og:site_name\" content=\"Smu\u010darski klub Cerknica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/skcerknica\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-15T10:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-29T10:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/Otepaa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"112\" \/>\n\t<meta property=\"og:image:height\" content=\"103\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Leon Zalar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Leon Zalar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/\"},\"author\":{\"name\":\"Leon Zalar\",\"@id\":\"https:\/\/ski.cerknica.net\/#\/schema\/person\/d3746bf9cf1c47213f020919cf9c44e4\"},\"headline\":\"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji\",\"datePublished\":\"2024-03-15T10:21:00+00:00\",\"dateModified\":\"2024-03-29T10:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/\"},\"wordCount\":94,\"publisher\":{\"@id\":\"https:\/\/ski.cerknica.net\/#organization\"},\"keywords\":[\"biatlon\",\"Manca Caserman\",\"svetovno prvenstvo\"],\"articleSection\":[\"Tekme\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/\",\"url\":\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/\",\"name\":\"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji - Smu\u010darski klub Cerknica\",\"isPartOf\":{\"@id\":\"https:\/\/ski.cerknica.net\/#website\"},\"datePublished\":\"2024-03-15T10:21:00+00:00\",\"dateModified\":\"2024-03-29T10:28:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ski.cerknica.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ski.cerknica.net\/#website\",\"url\":\"https:\/\/ski.cerknica.net\/\",\"name\":\"Smu\u010darski klub Cerknica\",\"description\":\"Klub veselih smu\u010darjev :)\",\"publisher\":{\"@id\":\"https:\/\/ski.cerknica.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ski.cerknica.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ski.cerknica.net\/#organization\",\"name\":\"Smu\u010darski klub Cerknica\",\"url\":\"https:\/\/ski.cerknica.net\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/skcerknica\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ski.cerknica.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2017\/10\/logo_black.jpg\",\"contentUrl\":\"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2017\/10\/logo_black.jpg\",\"width\":950,\"height\":960,\"caption\":\"Smu\u010darski klub Cerknica\"},\"image\":{\"@id\":\"https:\/\/ski.cerknica.net\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/ski.cerknica.net\/#\/schema\/person\/d3746bf9cf1c47213f020919cf9c44e4\",\"name\":\"Leon Zalar\",\"url\":\"https:\/\/ski.cerknica.net\/index.php\/author\/leonz\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji - Smu\u010darski klub Cerknica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/","og_locale":"en_US","og_type":"article","og_title":"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji - Smu\u010darski klub Cerknica","og_description":"Na mladinskem svetovnem prvenstvu, ki je od 23. februarja do 2. marca 2024 potekalo v Otep\u00e4\u00e4ju, Estonija, je slovenske barve zastopala tudi na\u0161a biatlonka Manca Caserman. Na vseh treh preizku\u0161njah je od slovenskih predstavnic dosegla najbolj\u0161o uvrstitev: 12. mesto na tekmi posamezno 10 km, 17. mesto na sprintu 6 km in 20. mesto na skupinski [&hellip;]","og_url":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/","og_site_name":"Smu\u010darski klub Cerknica","article_publisher":"https:\/\/www.facebook.com\/skcerknica\/","article_published_time":"2024-03-15T10:21:00+00:00","article_modified_time":"2024-03-29T10:28:01+00:00","og_image":[{"width":112,"height":103,"url":"http:\/\/ski.cerknica.net\/wp-content\/uploads\/2024\/03\/Otepaa.png","type":"image\/png"}],"author":"Leon Zalar","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Leon Zalar","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/#article","isPartOf":{"@id":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/"},"author":{"name":"Leon Zalar","@id":"https:\/\/ski.cerknica.net\/#\/schema\/person\/d3746bf9cf1c47213f020919cf9c44e4"},"headline":"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji","datePublished":"2024-03-15T10:21:00+00:00","dateModified":"2024-03-29T10:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/"},"wordCount":94,"publisher":{"@id":"https:\/\/ski.cerknica.net\/#organization"},"keywords":["biatlon","Manca Caserman","svetovno prvenstvo"],"articleSection":["Tekme"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/","url":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/","name":"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji - Smu\u010darski klub Cerknica","isPartOf":{"@id":"https:\/\/ski.cerknica.net\/#website"},"datePublished":"2024-03-15T10:21:00+00:00","dateModified":"2024-03-29T10:28:01+00:00","breadcrumb":{"@id":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ski.cerknica.net\/index.php\/2024\/03\/15\/manca-caserman-zastopala-slovenijo-na-ibu-mladinskem-svetovnem-prvenstvu-v-estoniji\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ski.cerknica.net\/"},{"@type":"ListItem","position":2,"name":"Manca Caserman zastopala Slovenijo na IBU mladinskem svetovnem prvenstvu v Estoniji"}]},{"@type":"WebSite","@id":"https:\/\/ski.cerknica.net\/#website","url":"https:\/\/ski.cerknica.net\/","name":"Smu\u010darski klub Cerknica","description":"Klub veselih smu\u010darjev :)","publisher":{"@id":"https:\/\/ski.cerknica.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ski.cerknica.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ski.cerknica.net\/#organization","name":"Smu\u010darski klub Cerknica","url":"https:\/\/ski.cerknica.net\/","sameAs":["https:\/\/www.facebook.com\/skcerknica\/"],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ski.cerknica.net\/#\/schema\/logo\/image\/","url":"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2017\/10\/logo_black.jpg","contentUrl":"https:\/\/ski.cerknica.net\/wp-content\/uploads\/2017\/10\/logo_black.jpg","width":950,"height":960,"caption":"Smu\u010darski klub Cerknica"},"image":{"@id":"https:\/\/ski.cerknica.net\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ski.cerknica.net\/#\/schema\/person\/d3746bf9cf1c47213f020919cf9c44e4","name":"Leon Zalar","url":"https:\/\/ski.cerknica.net\/index.php\/author\/leonz\/"}]}},"_links":{"self":[{"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/posts\/617"}],"collection":[{"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/comments?post=617"}],"version-history":[{"count":2,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/posts\/617\/revisions"}],"predecessor-version":[{"id":621,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/posts\/617\/revisions\/621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/media\/623"}],"wp:attachment":[{"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/media?parent=617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/categories?post=617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ski.cerknica.net\/index.php\/wp-json\/wp\/v2\/tags?post=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}